{"id":738,"date":"2022-03-20T18:20:34","date_gmt":"2022-03-20T17:20:34","guid":{"rendered":"https:\/\/www.linux-werkstatt-oldenburg.de\/?p=738"},"modified":"2022-03-21T20:20:10","modified_gmt":"2022-03-21T19:20:10","slug":"e-mail-verschluesselung-pgp-unter-linux-fuer-einsteiger","status":"publish","type":"post","link":"https:\/\/www.linux-werkstatt-oldenburg.de\/index.php\/2022\/03\/20\/e-mail-verschluesselung-pgp-unter-linux-fuer-einsteiger\/","title":{"rendered":"E-Mail Verschl\u00fcsselung (PGP) unter Linux f\u00fcr Einsteiger"},"content":{"rendered":"\n<p>Online-Workshop: E-Mail Verschl\u00fcsselung (PGP) unter Linux f\u00fcr Einsteiger<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-large is-resized\"><a href=\"https:\/\/www.linux-werkstatt-oldenburg.de\/wp-content\/uploads\/2022\/03\/emailverschluesselungfuereinsteiger.png\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.linux-werkstatt-oldenburg.de\/wp-content\/uploads\/2022\/03\/emailverschluesselungfuereinsteiger-1024x577.png\" alt=\"\" class=\"wp-image-743\" width=\"627\" height=\"352\" srcset=\"https:\/\/www.linux-werkstatt-oldenburg.de\/wp-content\/uploads\/2022\/03\/emailverschluesselungfuereinsteiger-1024x577.png 1024w, https:\/\/www.linux-werkstatt-oldenburg.de\/wp-content\/uploads\/2022\/03\/emailverschluesselungfuereinsteiger-300x169.png 300w\" sizes=\"auto, (max-width: 627px) 100vw, 627px\" \/><\/a><figcaption>E-Mail Verschl\u00fcsselung<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Inhalte:<\/h3>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Theorie 1: wie funktioniert die Verschl\u00fcsselung\/Signatur?<\/li><li>Praxis 1: E-Mail Verschl\u00fcsselung mit Thunderbird (PGP)<\/li><li>Erzeugen\/Sichern der Schl\u00fcssel<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Senden \/ Empfangen<\/li><li>Theorie 2: Wem geh\u00f6rt welcher Schl\u00fcssel?<\/li><li>Praxis 2: Pr\u00fcfung von Schl\u00fcsseln<\/li><li>Ausblick: Einsatz einer Smartcard (OpenPGP)<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Teilnehmer ben\u00f6tigen:<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>eine E-Mail Adresse und das zugeh\u00f6rige Passwort<\/li><li>Das installierte E-Mail Programm Thunderbird unter Linux<\/li><li>Browser\/Internetzugang f\u00fcr die Teilnahme an der Videokonferenz<\/li><\/ul>\n\n\n\n<p>Datum: 31.03.2022<br>Uhrzeit: 20.00 Uhr<br>Dauer: 120 Minuten<br>Maximale Teilnehmerzahl: 6<br>Ort: Die Adresse f\u00fcr die Videokonferenz wird erst ca. 30 Minuten vor dem Start bekannt gegeben<\/p>\n\n\n\n<p>Interessenten melden sich bitte per E-Mail bei <a href=\"mailto:f_slotta@gmx.de\">Frank<\/a> an, es entstehen keine Kosten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Online-Workshop: E-Mail Verschl\u00fcsselung (PGP) unter Linux f\u00fcr Einsteiger Inhalte: Theorie 1: wie funktioniert die Verschl\u00fcsselung\/Signatur? Praxis 1: E-Mail Verschl\u00fcsselung mit Thunderbird (PGP) Erzeugen\/Sichern der Schl\u00fcssel Senden \/ Empfangen Theorie 2: Wem geh\u00f6rt welcher Schl\u00fcssel? Praxis 2: Pr\u00fcfung von Schl\u00fcsseln Ausblick: Einsatz einer Smartcard (OpenPGP) Teilnehmer ben\u00f6tigen: eine E-Mail Adresse und das zugeh\u00f6rige Passwort Das installierte [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-738","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.linux-werkstatt-oldenburg.de\/index.php\/wp-json\/wp\/v2\/posts\/738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.linux-werkstatt-oldenburg.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.linux-werkstatt-oldenburg.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.linux-werkstatt-oldenburg.de\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.linux-werkstatt-oldenburg.de\/index.php\/wp-json\/wp\/v2\/comments?post=738"}],"version-history":[{"count":4,"href":"https:\/\/www.linux-werkstatt-oldenburg.de\/index.php\/wp-json\/wp\/v2\/posts\/738\/revisions"}],"predecessor-version":[{"id":746,"href":"https:\/\/www.linux-werkstatt-oldenburg.de\/index.php\/wp-json\/wp\/v2\/posts\/738\/revisions\/746"}],"wp:attachment":[{"href":"https:\/\/www.linux-werkstatt-oldenburg.de\/index.php\/wp-json\/wp\/v2\/media?parent=738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.linux-werkstatt-oldenburg.de\/index.php\/wp-json\/wp\/v2\/categories?post=738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.linux-werkstatt-oldenburg.de\/index.php\/wp-json\/wp\/v2\/tags?post=738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}